{"id":64,"count":1,"description":"","link":"https:\/\/anime-roulette.com\/blog\/tag\/netflix-anime\/","name":"Netflix Anime","slug":"netflix-anime","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Netflix Anime Archives - Anime Roulette Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anime-roulette.com\/blog\/tag\/netflix-anime\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netflix Anime Archives - Anime Roulette Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anime-roulette.com\/blog\/tag\/netflix-anime\/\" \/>\n<meta property=\"og:site_name\" content=\"Anime Roulette Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/anime-roulette.com\\\/blog\\\/tag\\\/netflix-anime\\\/\",\"url\":\"https:\\\/\\\/anime-roulette.com\\\/blog\\\/tag\\\/netflix-anime\\\/\",\"name\":\"Netflix Anime Archives - Anime Roulette Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anime-roulette.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anime-roulette.com\\\/blog\\\/tag\\\/netflix-anime\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anime-roulette.com\\\/blog\\\/tag\\\/netflix-anime\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anime-roulette.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Netflix Anime\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anime-roulette.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/anime-roulette.com\\\/blog\\\/\",\"name\":\"Anime Roulette Blog\",\"description\":\"Discover Your Next Anime\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anime-roulette.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netflix Anime Archives - Anime Roulette Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anime-roulette.com\/blog\/tag\/netflix-anime\/","og_locale":"en_US","og_type":"article","og_title":"Netflix Anime Archives - Anime Roulette Blog","og_url":"https:\/\/anime-roulette.com\/blog\/tag\/netflix-anime\/","og_site_name":"Anime Roulette Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/anime-roulette.com\/blog\/tag\/netflix-anime\/","url":"https:\/\/anime-roulette.com\/blog\/tag\/netflix-anime\/","name":"Netflix Anime Archives - Anime Roulette Blog","isPartOf":{"@id":"https:\/\/anime-roulette.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/anime-roulette.com\/blog\/tag\/netflix-anime\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/anime-roulette.com\/blog\/tag\/netflix-anime\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anime-roulette.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Netflix Anime"}]},{"@type":"WebSite","@id":"https:\/\/anime-roulette.com\/blog\/#website","url":"https:\/\/anime-roulette.com\/blog\/","name":"Anime Roulette Blog","description":"Discover Your Next Anime","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anime-roulette.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/anime-roulette.com\/blog\/wp-json\/wp\/v2\/tags\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anime-roulette.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/anime-roulette.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/anime-roulette.com\/blog\/wp-json\/wp\/v2\/posts?tags=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}